{"id":7686,"date":"2024-06-05T21:15:28","date_gmt":"2024-06-05T19:15:28","guid":{"rendered":"https:\/\/grundschule-heinsberg.de\/udhetim-ne-rrethin-olpe\/"},"modified":"2025-06-10T10:14:33","modified_gmt":"2025-06-10T08:14:33","slug":"udhetim-ne-rrethin-olpe","status":"publish","type":"post","link":"https:\/\/grundschule-heinsberg.de\/sq\/udhetim-ne-rrethin-olpe\/","title":{"rendered":"Udh\u00ebtim n\u00eb rrethin Olpe"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"7686\" class=\"elementor elementor-7686 elementor-7493\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-34dba45 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"34dba45\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-84b1b4e\" data-id=\"84b1b4e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2c84795 elementor-widget elementor-widget-text-editor\" data-id=\"2c84795\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>K\u00ebt\u00eb vit klasat e klas\u00ebs s\u00eb tret\u00eb shkuan s\u00ebrish n\u00eb nj\u00eb udh\u00ebtim n\u00eb rrethin Olpe.<\/p><p style=\"text-align: left;\">Filloi n\u00eb Altenhundem n\u00eb stacionin e trenit. Nga atje, pas nj\u00eb ndalese t\u00eb shkurt\u00ebr n\u00eb Finnentrop, shkuam n\u00eb Attendorn. Nx\u00ebn\u00ebsit e klas\u00ebs s\u00eb tret\u00eb vizituan Shpell\u00ebn Atta. Gjat\u00eb turneut ata m\u00ebsuan shum\u00eb p\u00ebr stalaktitet dhe krijimin dhe zbulimin e shpell\u00ebs. Pas nj\u00eb pushimi n\u00eb k\u00ebndin e loj\u00ebrave aty pran\u00eb, vazhdojm\u00eb me Biggolino n\u00eb bank\u00ebn e anijes. M\u00eb pas mor\u00ebm anijen p\u00ebrtej Biggesee p\u00ebr n\u00eb Sondern. N\u00eb fund, klasat 3a dhe 3b u kthyen me makin\u00eb nga Sondern n\u00eb Altenhundem.<\/p><p style=\"text-align: center;\">Ajo ishte nj\u00eb dit\u00eb e mrekullueshme!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0060826 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0060826\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-835c715\" data-id=\"835c715\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8c0677a elementor-widget elementor-widget-image\" data-id=\"8c0677a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2773-1024x768.jpeg\" class=\"attachment-large size-large wp-image-8244\" alt=\"\" srcset=\"https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2773-1024x768.jpeg 1024w, https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2773-300x225.jpeg 300w, https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2773-768x576.jpeg 768w, https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2773.jpeg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-adbfe4a\" data-id=\"adbfe4a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74fe629 elementor-widget elementor-widget-image\" data-id=\"74fe629\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2777-1024x768.jpeg\" class=\"attachment-large size-large wp-image-8252\" alt=\"\" srcset=\"https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2777-1024x768.jpeg 1024w, https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2777-300x225.jpeg 300w, https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2777-768x576.jpeg 768w, https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2777.jpeg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-caea471 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"caea471\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0b7cc37\" data-id=\"0b7cc37\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d12dec elementor-widget elementor-widget-image\" data-id=\"5d12dec\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2782-1024x768.jpeg\" class=\"attachment-large size-large wp-image-8268\" alt=\"\" srcset=\"https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2782-1024x768.jpeg 1024w, https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2782-300x225.jpeg 300w, https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2782-768x576.jpeg 768w, https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2782.jpeg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-719defa\" data-id=\"719defa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fa56d7f elementor-widget elementor-widget-image\" data-id=\"fa56d7f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2788-1024x768.jpeg\" class=\"attachment-large size-large wp-image-8276\" alt=\"\" srcset=\"https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2788-1024x768.jpeg 1024w, https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2788-300x225.jpeg 300w, https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2788-768x576.jpeg 768w, https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2788.jpeg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-043f0c3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"043f0c3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0143beb\" data-id=\"0143beb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e2fadc elementor-widget elementor-widget-image\" data-id=\"7e2fadc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2790-1024x768.jpeg\" class=\"attachment-large size-large wp-image-8284\" alt=\"\" srcset=\"https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2790-1024x768.jpeg 1024w, https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2790-300x225.jpeg 300w, https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2790-768x576.jpeg 768w, https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2790.jpeg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-31a4e06\" data-id=\"31a4e06\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dd910cf elementor-widget elementor-widget-image\" data-id=\"dd910cf\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2794-1024x768.jpeg\" class=\"attachment-large size-large wp-image-8292\" alt=\"\" srcset=\"https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2794-1024x768.jpeg 1024w, https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2794-300x225.jpeg 300w, https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2794-768x576.jpeg 768w, https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2794.jpeg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1115267 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1115267\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8ef4bd3\" data-id=\"8ef4bd3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40a10d9 elementor-widget elementor-widget-image\" data-id=\"40a10d9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2780-768x1024.jpeg\" class=\"attachment-large size-large wp-image-8260\" alt=\"\" srcset=\"https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2780-768x1024.jpeg 768w, https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2780-225x300.jpeg 225w, https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2780-rotated.jpeg 900w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-95a511b\" data-id=\"95a511b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c927fa elementor-widget elementor-widget-image\" data-id=\"9c927fa\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2800-768x1024.jpeg\" class=\"attachment-large size-large wp-image-8308\" alt=\"\" srcset=\"https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2800-768x1024.jpeg 768w, https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2800-225x300.jpeg 225w, https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2800-rotated.jpeg 900w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3b21827 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3b21827\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-11b82be\" data-id=\"11b82be\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-666229b elementor-widget elementor-widget-image\" data-id=\"666229b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2802-1024x768.jpeg\" class=\"attachment-large size-large wp-image-8316\" alt=\"\" srcset=\"https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2802-1024x768.jpeg 1024w, https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2802-300x225.jpeg 300w, https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2802-768x576.jpeg 768w, https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2802.jpeg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-97ac599\" data-id=\"97ac599\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bc42d7f elementor-widget elementor-widget-image\" data-id=\"bc42d7f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/e9c8b78e-1b02-4bd7-a01e-e3fe27325ecb-4-1024x768.jpg\" class=\"attachment-large size-large wp-image-8236\" alt=\"\" srcset=\"https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/e9c8b78e-1b02-4bd7-a01e-e3fe27325ecb-4-1024x768.jpg 1024w, https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/e9c8b78e-1b02-4bd7-a01e-e3fe27325ecb-4-300x225.jpg 300w, https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/e9c8b78e-1b02-4bd7-a01e-e3fe27325ecb-4-768x576.jpg 768w, https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/e9c8b78e-1b02-4bd7-a01e-e3fe27325ecb-4.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-59dd4b2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"59dd4b2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0ae9a4c\" data-id=\"0ae9a4c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-98c3ef1 elementor-widget elementor-widget-image\" data-id=\"98c3ef1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2810-768x1024.jpeg\" class=\"attachment-large size-large wp-image-8324\" alt=\"\" srcset=\"https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2810-768x1024.jpeg 768w, https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2810-225x300.jpeg 225w, https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2810-rotated.jpeg 900w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-360e366\" data-id=\"360e366\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-28c4dff elementor-widget elementor-widget-image\" data-id=\"28c4dff\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2815-768x1024.jpeg\" class=\"attachment-large size-large wp-image-8332\" alt=\"\" srcset=\"https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2815-768x1024.jpeg 768w, https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2815-225x300.jpeg 225w, https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2815-rotated.jpeg 900w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d1b8bd0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d1b8bd0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e9fcd7f\" data-id=\"e9fcd7f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ebaa5b elementor-widget elementor-widget-image\" data-id=\"7ebaa5b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2820-768x1024.jpeg\" class=\"attachment-large size-large wp-image-8340\" alt=\"\" srcset=\"https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2820-768x1024.jpeg 768w, https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2820-225x300.jpeg 225w, https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2820-rotated.jpeg 900w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-180b72e\" data-id=\"180b72e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d7bc520 elementor-widget elementor-widget-image\" data-id=\"d7bc520\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2831-768x1024.jpeg\" class=\"attachment-large size-large wp-image-8348\" alt=\"\" srcset=\"https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2831-768x1024.jpeg 768w, https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2831-225x300.jpeg 225w, https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2831-rotated.jpeg 900w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>K\u00ebt\u00eb vit klasat e klas\u00ebs s\u00eb tret\u00eb shkuan s\u00ebrish n\u00eb nj\u00eb udh\u00ebtim n\u00eb rrethin Olpe. Filloi n\u00eb Altenhundem n\u00eb stacionin e trenit. Nga atje, pas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8308,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[106,105],"tags":[],"class_list":["post-7686","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2024-sq","category-ngjarjet"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Udh\u00ebtim n\u00eb rrethin Olpe - St. Katharina Grundschule Heinsberg<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/grundschule-heinsberg.de\/sq\/udhetim-ne-rrethin-olpe\/\" \/>\n<meta property=\"og:locale\" content=\"sq_AL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Udh\u00ebtim n\u00eb rrethin Olpe - St. Katharina Grundschule Heinsberg\" \/>\n<meta property=\"og:description\" content=\"K\u00ebt\u00eb vit klasat e klas\u00ebs s\u00eb tret\u00eb shkuan s\u00ebrish n\u00eb nj\u00eb udh\u00ebtim n\u00eb rrethin Olpe. Filloi n\u00eb Altenhundem n\u00eb stacionin e trenit. Nga atje, pas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/grundschule-heinsberg.de\/sq\/udhetim-ne-rrethin-olpe\/\" \/>\n<meta property=\"og:site_name\" content=\"St. Katharina Grundschule Heinsberg\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-05T19:15:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-10T08:14:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2023\/03\/head_aussenansicht-grundschule-heinsberg.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"810\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ulrike G\u00f6bel-Kohtz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ulrike G\u00f6bel-Kohtz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/grundschule-heinsberg.de\\\/sq\\\/udhetim-ne-rrethin-olpe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grundschule-heinsberg.de\\\/sq\\\/udhetim-ne-rrethin-olpe\\\/\"},\"author\":{\"name\":\"Ulrike G\u00f6bel-Kohtz\",\"@id\":\"https:\\\/\\\/grundschule-heinsberg.de\\\/sq\\\/#\\\/schema\\\/person\\\/9acfc4936904276e9247a22cb3de5627\"},\"headline\":\"Udh\u00ebtim n\u00eb rrethin Olpe\",\"datePublished\":\"2024-06-05T19:15:28+00:00\",\"dateModified\":\"2025-06-10T08:14:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/grundschule-heinsberg.de\\\/sq\\\/udhetim-ne-rrethin-olpe\\\/\"},\"wordCount\":123,\"publisher\":{\"@id\":\"https:\\\/\\\/grundschule-heinsberg.de\\\/sq\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/grundschule-heinsberg.de\\\/sq\\\/udhetim-ne-rrethin-olpe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grundschule-heinsberg.de\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/IMG_2800-rotated.jpeg\",\"articleSection\":[\"2024\",\"Ngjarjet\"],\"inLanguage\":\"sq-AL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/grundschule-heinsberg.de\\\/sq\\\/udhetim-ne-rrethin-olpe\\\/\",\"url\":\"https:\\\/\\\/grundschule-heinsberg.de\\\/sq\\\/udhetim-ne-rrethin-olpe\\\/\",\"name\":\"Udh\u00ebtim n\u00eb rrethin Olpe - St. Katharina Grundschule Heinsberg\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grundschule-heinsberg.de\\\/sq\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/grundschule-heinsberg.de\\\/sq\\\/udhetim-ne-rrethin-olpe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/grundschule-heinsberg.de\\\/sq\\\/udhetim-ne-rrethin-olpe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grundschule-heinsberg.de\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/IMG_2800-rotated.jpeg\",\"datePublished\":\"2024-06-05T19:15:28+00:00\",\"dateModified\":\"2025-06-10T08:14:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/grundschule-heinsberg.de\\\/sq\\\/udhetim-ne-rrethin-olpe\\\/#breadcrumb\"},\"inLanguage\":\"sq-AL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/grundschule-heinsberg.de\\\/sq\\\/udhetim-ne-rrethin-olpe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"sq-AL\",\"@id\":\"https:\\\/\\\/grundschule-heinsberg.de\\\/sq\\\/udhetim-ne-rrethin-olpe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/grundschule-heinsberg.de\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/IMG_2800-rotated.jpeg\",\"contentUrl\":\"https:\\\/\\\/grundschule-heinsberg.de\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/IMG_2800-rotated.jpeg\",\"width\":900,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/grundschule-heinsberg.de\\\/sq\\\/udhetim-ne-rrethin-olpe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/grundschule-heinsberg.de\\\/sq\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Udh\u00ebtim n\u00eb rrethin Olpe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/grundschule-heinsberg.de\\\/sq\\\/#website\",\"url\":\"https:\\\/\\\/grundschule-heinsberg.de\\\/sq\\\/\",\"name\":\"St. Katharina Grundschule Heinsberg\",\"description\":\"f\u00fcreinander, voneinander, gemeinsam und individuell: Hand in Hand auf dem Weg in die Zukunft\",\"publisher\":{\"@id\":\"https:\\\/\\\/grundschule-heinsberg.de\\\/sq\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/grundschule-heinsberg.de\\\/sq\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sq-AL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/grundschule-heinsberg.de\\\/sq\\\/#organization\",\"name\":\"St. Katharina Grundschule Heinsberg\",\"url\":\"https:\\\/\\\/grundschule-heinsberg.de\\\/sq\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sq-AL\",\"@id\":\"https:\\\/\\\/grundschule-heinsberg.de\\\/sq\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/grundschule-heinsberg.de\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/230307_Grundschule-Heinsberg_Logo_RGB.svg\",\"contentUrl\":\"https:\\\/\\\/grundschule-heinsberg.de\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/230307_Grundschule-Heinsberg_Logo_RGB.svg\",\"width\":311,\"height\":135,\"caption\":\"St. Katharina Grundschule Heinsberg\"},\"image\":{\"@id\":\"https:\\\/\\\/grundschule-heinsberg.de\\\/sq\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/grundschule-heinsberg.de\\\/sq\\\/#\\\/schema\\\/person\\\/9acfc4936904276e9247a22cb3de5627\",\"name\":\"Ulrike G\u00f6bel-Kohtz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sq-AL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/89064bb57430127056a72e7af3cc87e5f92d3b115a22e6576cb2be788dd4fac3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/89064bb57430127056a72e7af3cc87e5f92d3b115a22e6576cb2be788dd4fac3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/89064bb57430127056a72e7af3cc87e5f92d3b115a22e6576cb2be788dd4fac3?s=96&d=mm&r=g\",\"caption\":\"Ulrike G\u00f6bel-Kohtz\"},\"url\":\"https:\\\/\\\/grundschule-heinsberg.de\\\/sq\\\/author\\\/goebel-kohtz\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Udh\u00ebtim n\u00eb rrethin Olpe - St. Katharina Grundschule Heinsberg","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/grundschule-heinsberg.de\/sq\/udhetim-ne-rrethin-olpe\/","og_locale":"sq_AL","og_type":"article","og_title":"Udh\u00ebtim n\u00eb rrethin Olpe - St. Katharina Grundschule Heinsberg","og_description":"K\u00ebt\u00eb vit klasat e klas\u00ebs s\u00eb tret\u00eb shkuan s\u00ebrish n\u00eb nj\u00eb udh\u00ebtim n\u00eb rrethin Olpe. Filloi n\u00eb Altenhundem n\u00eb stacionin e trenit. Nga atje, pas [&hellip;]","og_url":"https:\/\/grundschule-heinsberg.de\/sq\/udhetim-ne-rrethin-olpe\/","og_site_name":"St. Katharina Grundschule Heinsberg","article_published_time":"2024-06-05T19:15:28+00:00","article_modified_time":"2025-06-10T08:14:33+00:00","og_image":[{"width":1080,"height":810,"url":"https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2023\/03\/head_aussenansicht-grundschule-heinsberg.jpg","type":"image\/jpeg"}],"author":"Ulrike G\u00f6bel-Kohtz","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Ulrike G\u00f6bel-Kohtz","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/grundschule-heinsberg.de\/sq\/udhetim-ne-rrethin-olpe\/#article","isPartOf":{"@id":"https:\/\/grundschule-heinsberg.de\/sq\/udhetim-ne-rrethin-olpe\/"},"author":{"name":"Ulrike G\u00f6bel-Kohtz","@id":"https:\/\/grundschule-heinsberg.de\/sq\/#\/schema\/person\/9acfc4936904276e9247a22cb3de5627"},"headline":"Udh\u00ebtim n\u00eb rrethin Olpe","datePublished":"2024-06-05T19:15:28+00:00","dateModified":"2025-06-10T08:14:33+00:00","mainEntityOfPage":{"@id":"https:\/\/grundschule-heinsberg.de\/sq\/udhetim-ne-rrethin-olpe\/"},"wordCount":123,"publisher":{"@id":"https:\/\/grundschule-heinsberg.de\/sq\/#organization"},"image":{"@id":"https:\/\/grundschule-heinsberg.de\/sq\/udhetim-ne-rrethin-olpe\/#primaryimage"},"thumbnailUrl":"https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2800-rotated.jpeg","articleSection":["2024","Ngjarjet"],"inLanguage":"sq-AL"},{"@type":"WebPage","@id":"https:\/\/grundschule-heinsberg.de\/sq\/udhetim-ne-rrethin-olpe\/","url":"https:\/\/grundschule-heinsberg.de\/sq\/udhetim-ne-rrethin-olpe\/","name":"Udh\u00ebtim n\u00eb rrethin Olpe - St. Katharina Grundschule Heinsberg","isPartOf":{"@id":"https:\/\/grundschule-heinsberg.de\/sq\/#website"},"primaryImageOfPage":{"@id":"https:\/\/grundschule-heinsberg.de\/sq\/udhetim-ne-rrethin-olpe\/#primaryimage"},"image":{"@id":"https:\/\/grundschule-heinsberg.de\/sq\/udhetim-ne-rrethin-olpe\/#primaryimage"},"thumbnailUrl":"https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2800-rotated.jpeg","datePublished":"2024-06-05T19:15:28+00:00","dateModified":"2025-06-10T08:14:33+00:00","breadcrumb":{"@id":"https:\/\/grundschule-heinsberg.de\/sq\/udhetim-ne-rrethin-olpe\/#breadcrumb"},"inLanguage":"sq-AL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/grundschule-heinsberg.de\/sq\/udhetim-ne-rrethin-olpe\/"]}]},{"@type":"ImageObject","inLanguage":"sq-AL","@id":"https:\/\/grundschule-heinsberg.de\/sq\/udhetim-ne-rrethin-olpe\/#primaryimage","url":"https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2800-rotated.jpeg","contentUrl":"https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2024\/06\/IMG_2800-rotated.jpeg","width":900,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/grundschule-heinsberg.de\/sq\/udhetim-ne-rrethin-olpe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/grundschule-heinsberg.de\/sq\/"},{"@type":"ListItem","position":2,"name":"Udh\u00ebtim n\u00eb rrethin Olpe"}]},{"@type":"WebSite","@id":"https:\/\/grundschule-heinsberg.de\/sq\/#website","url":"https:\/\/grundschule-heinsberg.de\/sq\/","name":"St. Katharina Grundschule Heinsberg","description":"f\u00fcreinander, voneinander, gemeinsam und individuell: Hand in Hand auf dem Weg in die Zukunft","publisher":{"@id":"https:\/\/grundschule-heinsberg.de\/sq\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/grundschule-heinsberg.de\/sq\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sq-AL"},{"@type":"Organization","@id":"https:\/\/grundschule-heinsberg.de\/sq\/#organization","name":"St. Katharina Grundschule Heinsberg","url":"https:\/\/grundschule-heinsberg.de\/sq\/","logo":{"@type":"ImageObject","inLanguage":"sq-AL","@id":"https:\/\/grundschule-heinsberg.de\/sq\/#\/schema\/logo\/image\/","url":"https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2023\/03\/230307_Grundschule-Heinsberg_Logo_RGB.svg","contentUrl":"https:\/\/grundschule-heinsberg.de\/wp-content\/uploads\/2023\/03\/230307_Grundschule-Heinsberg_Logo_RGB.svg","width":311,"height":135,"caption":"St. Katharina Grundschule Heinsberg"},"image":{"@id":"https:\/\/grundschule-heinsberg.de\/sq\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/grundschule-heinsberg.de\/sq\/#\/schema\/person\/9acfc4936904276e9247a22cb3de5627","name":"Ulrike G\u00f6bel-Kohtz","image":{"@type":"ImageObject","inLanguage":"sq-AL","@id":"https:\/\/secure.gravatar.com\/avatar\/89064bb57430127056a72e7af3cc87e5f92d3b115a22e6576cb2be788dd4fac3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/89064bb57430127056a72e7af3cc87e5f92d3b115a22e6576cb2be788dd4fac3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/89064bb57430127056a72e7af3cc87e5f92d3b115a22e6576cb2be788dd4fac3?s=96&d=mm&r=g","caption":"Ulrike G\u00f6bel-Kohtz"},"url":"https:\/\/grundschule-heinsberg.de\/sq\/author\/goebel-kohtz\/"}]}},"_links":{"self":[{"href":"https:\/\/grundschule-heinsberg.de\/sq\/wp-json\/wp\/v2\/posts\/7686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grundschule-heinsberg.de\/sq\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grundschule-heinsberg.de\/sq\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grundschule-heinsberg.de\/sq\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/grundschule-heinsberg.de\/sq\/wp-json\/wp\/v2\/comments?post=7686"}],"version-history":[{"count":0,"href":"https:\/\/grundschule-heinsberg.de\/sq\/wp-json\/wp\/v2\/posts\/7686\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grundschule-heinsberg.de\/sq\/wp-json\/wp\/v2\/media\/8308"}],"wp:attachment":[{"href":"https:\/\/grundschule-heinsberg.de\/sq\/wp-json\/wp\/v2\/media?parent=7686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grundschule-heinsberg.de\/sq\/wp-json\/wp\/v2\/categories?post=7686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grundschule-heinsberg.de\/sq\/wp-json\/wp\/v2\/tags?post=7686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}